{"id":1095,"count":1,"description":"","link":"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/","name":"interpersonal skills","slug":"interpersonal-skills","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>interpersonal skills archivos | Blue Manakin<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"interpersonal skills archivos | Blue Manakin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Manakin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@thebluemanakin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/\",\"url\":\"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/\",\"name\":\"interpersonal skills archivos | Blue Manakin\",\"isPartOf\":{\"@id\":\"https:\/\/thebluemanakin.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thebluemanakin.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"interpersonal skills\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thebluemanakin.com\/#website\",\"url\":\"https:\/\/thebluemanakin.com\/\",\"name\":\"Blue Manakin\",\"description\":\"Blue Manakin. Come Dance With Us!\",\"publisher\":{\"@id\":\"https:\/\/thebluemanakin.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thebluemanakin.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/thebluemanakin.com\/#organization\",\"name\":\"Blue Manakin\",\"url\":\"https:\/\/thebluemanakin.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/thebluemanakin.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/thebluemanakin.com\/wp-content\/uploads\/2021\/07\/cropped-logo-header.png\",\"contentUrl\":\"https:\/\/thebluemanakin.com\/wp-content\/uploads\/2021\/07\/cropped-logo-header.png\",\"width\":613,\"height\":250,\"caption\":\"Blue Manakin\"},\"image\":{\"@id\":\"https:\/\/thebluemanakin.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/thebluemanakin\",\"https:\/\/www.instagram.com\/thebluemanakin\/\",\"https:\/\/www.linkedin.com\/company\/blue-manakin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"interpersonal skills archivos | Blue Manakin","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"interpersonal skills archivos | Blue Manakin","og_url":"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/","og_site_name":"Blue Manakin","twitter_card":"summary_large_image","twitter_site":"@thebluemanakin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/","url":"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/","name":"interpersonal skills archivos | Blue Manakin","isPartOf":{"@id":"https:\/\/thebluemanakin.com\/#website"},"breadcrumb":{"@id":"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thebluemanakin.com\/en\/blog\/tag\/interpersonal-skills\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebluemanakin.com\/"},{"@type":"ListItem","position":2,"name":"interpersonal skills"}]},{"@type":"WebSite","@id":"https:\/\/thebluemanakin.com\/#website","url":"https:\/\/thebluemanakin.com\/","name":"Blue Manakin","description":"Blue Manakin. Come Dance With Us!","publisher":{"@id":"https:\/\/thebluemanakin.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebluemanakin.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/thebluemanakin.com\/#organization","name":"Blue Manakin","url":"https:\/\/thebluemanakin.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thebluemanakin.com\/#\/schema\/logo\/image\/","url":"https:\/\/thebluemanakin.com\/wp-content\/uploads\/2021\/07\/cropped-logo-header.png","contentUrl":"https:\/\/thebluemanakin.com\/wp-content\/uploads\/2021\/07\/cropped-logo-header.png","width":613,"height":250,"caption":"Blue Manakin"},"image":{"@id":"https:\/\/thebluemanakin.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/thebluemanakin","https:\/\/www.instagram.com\/thebluemanakin\/","https:\/\/www.linkedin.com\/company\/blue-manakin"]}]}},"_links":{"self":[{"href":"https:\/\/thebluemanakin.com\/en\/wp-json\/wp\/v2\/tags\/1095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebluemanakin.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thebluemanakin.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thebluemanakin.com\/en\/wp-json\/wp\/v2\/posts?tags=1095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}